{"id":1044506,"date":"2024-04-25T10:04:47","date_gmt":"2024-04-25T08:04:47","guid":{"rendered":"https:\/\/fk-secondhand.com\/shop\/certo-dollina-ii-mit-cessar-5cm-f-29-469087\/"},"modified":"2024-12-09T15:36:06","modified_gmt":"2024-12-09T14:36:06","slug":"certo-dollina-ii-mit-cessar-5cm-f-29-469087","status":"publish","type":"product","link":"https:\/\/fk-secondhand.com\/en\/shop\/certo-dollina-ii-mit-cessar-5cm-f-29-469087\/","title":{"rendered":"CERTO Dollina II mit Cessar 5cm f\/2,9 &#8211; #469087"},"content":{"rendered":"<table class=\"woocommerce-product-attributes shop_attributes\">\n<tbody>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Production Year(s)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1936 &#8211; 1941<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Type<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Rangefinder camera<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Film Format<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>135 (35mm film)<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Image Size<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>24x36mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focussing<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual focus<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Leaf shutter<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter Speed<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1\/300 &#8211; 1 sec.<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Exposure Control<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc empty\">\n<th>&nbsp;<\/th>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc no-pair\">\n<th>&nbsp;<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">Steinheil M\u00fcnchen Cessar<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focusing<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual focus<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focal Length<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>50mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Max. Aperture<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1:2.9<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Aperture Blades<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>10<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Close Focus Distance<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>0.9 m<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Dollina viewfinder camera made by Certo Dresden<\/p>\n","protected":false},"featured_media":1044497,"template":"","meta":[],"product_brand":[],"product_cat":[110],"product_tag":[],"class_list":["post-1044506","product","type-product","status-publish","has-post-thumbnail","product_cat-film-cameras","product_shipping_class-mail-up-to-2-kg","first","outofstock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product\/1044506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media\/1044497"}],"wp:attachment":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media?parent=1044506"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_brand?post=1044506"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_cat?post=1044506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_tag?post=1044506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}