{"id":1143534,"date":"2024-12-03T10:35:03","date_gmt":"2024-12-03T09:35:03","guid":{"rendered":"https:\/\/fk-secondhand.com\/shop\/panasonic-dc-gx9-digitalkamera-001112\/"},"modified":"2024-12-03T10:35:39","modified_gmt":"2024-12-03T09:35:39","slug":"panasonic-dc-gx9-digitalkamera-001112","status":"publish","type":"product","link":"https:\/\/fk-secondhand.com\/en\/shop\/panasonic-dc-gx9-digitalkamera-001112\/","title":{"rendered":"Panasonic DC-GX9 Digitalkamera &#8211; #001112"},"content":{"rendered":"<table class=\"woocommerce-product-attributes shop_attributes\">\n<tbody>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Introduced<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>2018<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Type<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Mirrorless System Camera<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Sensor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>CMOS (17,3 x 13,0)<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Pixel (effective)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>20.3 million pixel<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Image Size<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>(Micro-)Four-Thirds<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Crop Factor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>2,0x<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">ISO Sensitivity<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>200-25600<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Continuous Shooting<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 9.0 fps<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Electronic focal-plane shutter<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter Speed<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1\/4000-60 sec.<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Metering Methods<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Center-weighted integral, Matrix, Spot<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Exposure Control<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Full Auto, Auto Program, Time Value, Aperture Value, Manual<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">View Finder<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Electronic Viewfinder (EVF)<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Monitor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>3,0&#8243;<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">File Formats<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>JPEG, RAW, MPEG-4<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Video Recording<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>4K UHD (16:9, 3.840 x 2.160, 30p), Full-HD (1.920 x 1.080, 60p)<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Storage media<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Secure Digital &#8211; SDHC, Secure Digital &#8211; SDXC<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Flash<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Built-in <\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Power Source<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Li-Ion Battery<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Dimensions (WxHxD)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 124 x 72 x 47 mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Weight<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 450 g<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Mirrorless system camera made by Panasonic <\/p>\n<p>::: SHUTTER COUNT: about 10,350 shutter releases ::: <\/p>\n","protected":false},"featured_media":1143523,"template":"","meta":[],"product_brand":[],"product_cat":[111],"product_tag":[],"class_list":{"0":"post-1143534","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-digital-cameras","7":"product_shipping_class-mail-up-to-2-kg","8":"pa_marke-panasonic-en","10":"first","11":"outofstock","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product\/1143534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media\/1143523"}],"wp:attachment":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media?parent=1143534"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_brand?post=1143534"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_cat?post=1143534"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_tag?post=1143534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}