{"id":1384247,"date":"2026-07-15T13:37:01","date_gmt":"2026-07-15T11:37:01","guid":{"rendered":"https:\/\/fk-secondhand.com\/shop\/canon-eos-5d-mark-iv-633039001292\/"},"modified":"2026-07-15T13:37:32","modified_gmt":"2026-07-15T11:37:32","slug":"canon-eos-5d-mark-iv-633039001292","status":"publish","type":"product","link":"https:\/\/fk-secondhand.com\/en\/shop\/canon-eos-5d-mark-iv-633039001292\/","title":{"rendered":"Canon EOS 5D Mark IV &#8211; #633039001292"},"content":{"rendered":"<table class=\"woocommerce-product-attributes shop_attributes\">\n<tbody>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Introduced<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>2016<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Type<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>SLR Camera<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Sensor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>CMOS (36 x 24 mm)<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Pixel (effective)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>30 million pixel<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Image Size<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>35mm Full-Frame<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Image Processor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Digic 6+<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Bayonet<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Canon EF<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">ISO Sensitivity<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>100 &#8211; 32.000<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Continuous Shooting<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 7.0 fps<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Electronic focal-plane shutter<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter Speed<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>30 &#8211; 1\/8.000 sec.<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Metering Methods<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Multi-segment, Center-weighted, Spot<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Exposure Control<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Aperture Value, Full Auto, Auto Program, Scene Auto, Manual, Time Value<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">View Finder<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Optical, Pentaprism<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Monitor<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>3,2&#8243;<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Storage media<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Secure Digital &#8211; SD, Secure Digital &#8211; SDHC, Secure Digital &#8211; SDXC, Compact Flash &#8211; CF Type I, Compact Flash &#8211; CF Type II<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Flash<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Extern via Hot-shoe<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Terminal<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>3.5mm Jack, HDMI, PC Sync, USB<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Dimensions (WxHxD)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 151x116x76 mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Weight<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 890 g<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Canon full-frame DSLR camera &#8211; body only<\/p>\n<p>::: Shutter count: about 72.690 shutter releases :::<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[111],"product_tag":[],"class_list":["post-1384247","product","type-product","status-publish","product_cat-digital-cameras","product_shipping_class-mail-up-to-2-kg","pa_marke-canon-en","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product\/1384247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media?parent=1384247"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_brand?post=1384247"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_cat?post=1384247"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_tag?post=1384247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}