{"id":1402512,"date":"2026-09-01T09:47:56","date_gmt":"2026-09-01T07:47:56","guid":{"rendered":"https:\/\/fk-secondhand.com\/shop\/mamiya-rb67-professional-s-mit-sekor-c-90mm-f-38-c191661\/"},"modified":"2026-09-01T09:48:12","modified_gmt":"2026-09-01T07:48:12","slug":"mamiya-rb67-professional-s-mit-sekor-c-90mm-f-38-c191661","status":"publish","type":"product","link":"https:\/\/fk-secondhand.com\/en\/shop\/mamiya-rb67-professional-s-mit-sekor-c-90mm-f-38-c191661\/","title":{"rendered":"Mamiya RB67 Professional S mit Sekor C 90mm f\/3,8 &#8211; #C191661"},"content":{"rendered":"<table class=\"woocommerce-product-attributes shop_attributes\">\n<tbody>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Production Year(s)<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>from 1975<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Type<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>SLR camera<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Bayonet<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Mamiya RB<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Film Format<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>120 rollfilm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Image Size<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>6x7cm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focussing<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual focus<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Leaf shutter in lens<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Shutter Speed<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>depending on lens<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Exposure Control<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Other Features<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>rotating back<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Weight<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 1450g<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc empty\">\n<th>&nbsp;<\/th>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc no-pair\">\n<th>&nbsp;<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">Mamiya Sekor C 90mm f\/3.8<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Serial Number<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>97584<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focusing<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>Manual focus<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Focal Length<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>90mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Max. Aperture<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1:3.8<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Close Focus Distance<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>1.5m<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Filter Thread<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>77mm<\/p>\n<\/td>\n<\/tr>\n<tr class=\"woocommerce-product-attributes-item wr-product-desc\">\n<th class=\"woocommerce-product-attributes-item__label\">Weight<\/th>\n<td class=\"woocommerce-product-attributes-item__value\">\n<p>approx. 705g<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Mamiya RB67 Pro S Set consisting of:<\/p>\n<p>Mamiya RB67 Pro S body<br \/>\nMamiya waist level finder<br \/>\nMamiya Pro S 120 rollfilm magazine<br \/>\nMamiya Sekor C 90mm f\/3.8<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[110],"product_tag":[],"class_list":["post-1402512","product","type-product","status-publish","product_cat-film-cameras","pa_marke-mamiya-en","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product\/1402512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/media?parent=1402512"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_brand?post=1402512"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_cat?post=1402512"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fk-secondhand.com\/en\/wp-json\/wp\/v2\/product_tag?post=1402512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}